{"id":19098,"date":"2025-10-09T14:02:59","date_gmt":"2025-10-09T13:02:59","guid":{"rendered":"https:\/\/handson.pt\/?post_type=listing&#038;p=19098"},"modified":"2025-10-16T11:20:27","modified_gmt":"2025-10-16T10:20:27","slug":"lisbon-portrait-photo-walk-phelipe-paraense","status":"publish","type":"listing","link":"https:\/\/handson.pt\/pt\/workshop\/lisbon-portrait-photo-walk-phelipe-paraense\/","title":{"rendered":"Be Yourself - Passeio fotogr\u00e1fico de retrato em Lisboa | Aprende a ter confian\u00e7a e a expressar-se"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"19098\" class=\"elementor elementor-19098\" data-elementor-post-type=\"listing\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34c0e9d1 e-flex e-con-boxed e-con e-parent\" data-id=\"34c0e9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dbb8377 elementor-widget elementor-widget-text-editor\" data-id=\"7dbb8377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-start=\"452\" data-end=\"517\">Descobre a arte da fotografia de retrato aut\u00eantica em Lisboa<\/h2><p data-start=\"518\" data-end=\"903\">A fotografia de retrato \u00e9 muito mais do que captar rostos. Trata-se de <strong data-start=\"586\" data-end=\"653\">revelando personalidade, confian\u00e7a e emo\u00e7\u00e3o atrav\u00e9s da lente<\/strong> enquanto exploras os recantos mais bonitos e inspiradores de Lisboa. Esta viagem imersiva <strong data-start=\"732\" data-end=\"762\">Passeio fotogr\u00e1fico com retratos de Lisboa<\/strong> combina a explora\u00e7\u00e3o criativa com a express\u00e3o pessoal, guiando-te por ruas encantadoras e pontos de vista onde cada fotografia conta uma hist\u00f3ria.<\/p><h2 data-start=\"905\" data-end=\"953\">\u00a0<\/h2><h2 data-start=\"905\" data-end=\"953\">Uma experi\u00eancia de caminhada que aumenta a tua confian\u00e7a<\/h2><p data-start=\"954\" data-end=\"1436\">Este workshop foi concebido para todos os que pretendem <strong data-start=\"1004\" data-end=\"1043\">sente-se \u00e0 vontade em frente \u00e0 c\u00e2mara<\/strong> enquanto descobres a capital portuguesa. Percorrer\u00e1s os bairros hist\u00f3ricos da cidade, as ruelas coloridas e as esplanadas panor\u00e2micas, aprendendo a expressar confian\u00e7a e conforto naturais. Ao longo do percurso, Phelipe Paraense vai dar-te orienta\u00e7\u00f5es em tempo real sobre postura, express\u00e3o facial e linguagem corporal, transformando participantes t\u00edmidos em sujeitos descontra\u00eddos e confiantes.<\/p><h2 data-start=\"1438\" data-end=\"1479\">\u00a0<\/h2><h2 data-start=\"1438\" data-end=\"1479\">Aprende a expressar o teu \"eu\" aut\u00eantico<\/h2><p data-start=\"1480\" data-end=\"1813\">Durante a experi\u00eancia, vais explorar <strong data-start=\"1520\" data-end=\"1549\">t\u00e9cnicas de pose natural<\/strong>Aprende a conectar-te com a c\u00e2mara e descobre como pequenos ajustes na posi\u00e7\u00e3o do corpo e na mentalidade podem mudar toda a sensa\u00e7\u00e3o de um retrato. Tamb\u00e9m ganhar\u00e1s conhecimentos sobre como a ilumina\u00e7\u00e3o, o enquadramento e o movimento podem real\u00e7ar as tuas melhores carater\u00edsticas em cada fotografia com a experi\u00eancia de mais de 15 anos de Phelipe Paraense.<\/p><p data-start=\"1815\" data-end=\"2027\">A experi\u00eancia n\u00e3o \u00e9 apenas sobre fotografia, mas tamb\u00e9m sobre <strong data-start=\"1875\" data-end=\"1906\">criar uma confian\u00e7a genu\u00edna<\/strong> que perdura para al\u00e9m desta sess\u00e3o. Terminar\u00e1s o passeio sentindo-te mais \u00e0 vontade para ser fotografado em qualquer situa\u00e7\u00e3o.<\/p><h2 data-start=\"2029\" data-end=\"2071\">\u00a0<\/h2><h2 data-start=\"2029\" data-end=\"2071\">O que recebes depois do passeio fotogr\u00e1fico<\/h2><p data-start=\"2072\" data-end=\"2343\">Ap\u00f3s o workshop, receber\u00e1s uma cole\u00e7\u00e3o de retratos profissionais de alta resolu\u00e7\u00e3o que captam a tua personalidade e a ess\u00eancia de Lisboa. As tuas fotografias s\u00e3o entregues digitalmente no prazo de seis dias atrav\u00e9s de uma liga\u00e7\u00e3o privada \u00e0 nuvem, prontas para partilhar ou imprimir.<\/p><h3 data-start=\"2345\" data-end=\"2377\">Inclui na experi\u00eancia<\/h3><p data-start=\"2378\" data-end=\"2691\">Passeio fotogr\u00e1fico panor\u00e2mico por Lisboa atrav\u00e9s de miradouros ic\u00f3nicos e j\u00f3ias locais<br data-start=\"2446\" data-end=\"2449\" \/>Orienta\u00e7\u00e3o fotogr\u00e1fica pessoal e treino de confian\u00e7a<br data-start=\"2505\" data-end=\"2508\" \/>Retratos digitais de alta resolu\u00e7\u00e3o entregues no prazo de seis dias<br data-start=\"2570\" data-end=\"2573\" \/>Transfer\u00eancia privada para a nuvem de todas as imagens finais<br data-start=\"2618\" data-end=\"2621\" \/>T\u00e9cnicas pr\u00e1ticas de pose e express\u00e3o para uma confian\u00e7a duradoura<\/p><p data-start=\"2693\" data-end=\"2869\">Esta \u00e9 uma experi\u00eancia que mistura <strong data-start=\"2727\" data-end=\"2770\">criatividade, viagens e auto-express\u00e3o<\/strong>, deixando-te n\u00e3o s\u00f3 com fotografias deslumbrantes, mas tamb\u00e9m com a confian\u00e7a necess\u00e1ria para enfrentar qualquer c\u00e2mara com facilidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"author":574,"featured_media":19091,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[],"event_category":[],"service_category":[152],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[126],"class_list":["post-19098","listing","type-listing","status-publish","has-post-thumbnail","hentry","service_category-photo-video","region-lisbon-workshops"],"_links":{"self":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/19098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/users\/574"}],"replies":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/comments?post=19098"}],"version-history":[{"count":16,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/19098\/revisions"}],"predecessor-version":[{"id":19503,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/19098\/revisions\/19503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/media\/19091"}],"wp:attachment":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/media?parent=19098"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing_category?post=19098"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/event_category?post=19098"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/service_category?post=19098"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/rental_category?post=19098"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/classifieds_category?post=19098"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing_feature?post=19098"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/region?post=19098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}