{"id":55154,"date":"2026-07-15T16:34:59","date_gmt":"2026-07-15T15:34:59","guid":{"rendered":"https:\/\/handson.pt\/?post_type=listing&#038;p=55154"},"modified":"2026-07-15T17:55:35","modified_gmt":"2026-07-15T16:55:35","slug":"natural-perfume-workshop-lisbon","status":"publish","type":"listing","link":"https:\/\/handson.pt\/pt\/workshop\/natural-perfume-workshop-lisbon\/","title":{"rendered":"Workshop de Perfumes Naturais S\u00f3lidos e L\u00edquidos"},"content":{"rendered":"<p class=\"font-claude-response-body break-words whitespace-normal\">Workshop de perfume natural s\u00f3lido e l\u00edquido em Lisboa, na sede da Mind The Trash, na Rua de S\u00e3o Paulo, n.\u00ba 254, Cais do Sodr\u00e9, no dia 26 de setembro de 2026, das 10h00 \u00e0s 13h00. \u00c9 uma sess\u00e3o pr\u00e1tica de tr\u00eas horas, por 56 euros, ministrada pela Sandra Leit\u00e3o, formadora certificada pelo IEFP. Vais aprender os fundamentos da perfumaria natural, misturar \u00f3leos essenciais para criar aromas harmoniosos e duradouros e formular um perfume s\u00f3lido e um l\u00edquido que reflitam as tuas prefer\u00eancias pessoais, sem fragr\u00e2ncias sint\u00e9ticas. Todos os materiais est\u00e3o inclu\u00eddos, recebes um guia de receitas para levares para casa e o n\u00famero m\u00e1ximo de participantes \u00e9 de 15.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">A sess\u00e3o aborda as notas de fragr\u00e2ncia, desde as de cabe\u00e7a, passando pelas de cora\u00e7\u00e3o, at\u00e9 \u00e0s de fundo; como misturar \u00f3leos essenciais para criar acordes de perfume equilibrados; t\u00e9cnicas de formula\u00e7\u00e3o de perfumes naturais; e todo o processo de cria\u00e7\u00e3o de ambos os formatos. A Mind The Trash \u00e9 uma comunidade de Lisboa focada na sustentabilidade, dedicada a tornar um estilo de vida de baixo impacto simples, acess\u00edvel e inspirador, combinando aprendizagem pr\u00e1tica com um ambiente acolhedor e criativo que d\u00e1 aos participantes a confian\u00e7a necess\u00e1ria para continuarem a criar as suas pr\u00f3prias fragr\u00e2ncias naturais em casa.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"font-claude-response-body break-words whitespace-normal\">O que vais aprender<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\ud83c\udf38 O b\u00e1sico sobre as notas de perfume, incluindo as notas de cabe\u00e7a, de cora\u00e7\u00e3o e de fundo<br \/>\n\ud83c\udf38 Como combinar \u00f3leos essenciais para criar acordes de perfume equilibrados e harmoniosos<br \/>\n\ud83c\udf38 T\u00e9cnicas de formula\u00e7\u00e3o de perfumes naturais, tanto em formato s\u00f3lido como l\u00edquido<br \/>\n\ud83c\udf38 Como fazer um perfume s\u00f3lido e um perfume l\u00edquido \u00e0 tua medida<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"font-claude-response-body break-words whitespace-normal\">O que est\u00e1 inclu\u00eddo:<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\ud83e\uded9 Todos os materiais e ingredientes para a sess\u00e3o completa<br \/>\n\ud83d\udcd6 Guia de receitas para levares para casa<br \/>\n\ud83c\udf38 O teu perfume s\u00f3lido e o teu perfume l\u00edquido, feitos \u00e0 m\u00e3o, para levares para casa<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"font-claude-response-body break-words whitespace-normal\">O que levas<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Dois perfumes naturais feitos \u00e0 m\u00e3o, um s\u00f3lido e outro l\u00edquido, criados inteiramente de acordo com as tuas prefer\u00eancias, e um guia de receitas para que possas recriar e aperfei\u00e7oar os teus aromas exclusivos em casa.<\/p>","protected":false},"author":1991,"featured_media":55162,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[162,1173,1178],"event_category":[],"service_category":[149],"rental_category":[],"classifieds_category":[],"listing_feature":[177,360],"region":[126],"class_list":["post-55154","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_category-eco-friendly-workshops","listing_category-gift-an-experience","listing_category-made-by-hand","service_category-home-diy","listing_feature-artisanal-handmade-workshops","listing_feature-perfume-workshops","region-lisbon-workshops"],"_links":{"self":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/55154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/users\/1991"}],"replies":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/comments?post=55154"}],"version-history":[{"count":4,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/55154\/revisions"}],"predecessor-version":[{"id":55174,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing\/55154\/revisions\/55174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/media\/55162"}],"wp:attachment":[{"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/media?parent=55154"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing_category?post=55154"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/event_category?post=55154"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/service_category?post=55154"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/rental_category?post=55154"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/classifieds_category?post=55154"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/listing_feature?post=55154"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/handson.pt\/pt\/wp-json\/wp\/v2\/region?post=55154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}